{"id":869,"date":"2013-12-22T14:31:45","date_gmt":"2013-12-22T13:31:45","guid":{"rendered":"http:\/\/www.studiodontoiatricodominici.com\/it\/?page_id=869"},"modified":"2018-02-18T08:52:41","modified_gmt":"2018-02-18T07:52:41","slug":"ortodonzia-mobile","status":"publish","type":"page","link":"https:\/\/www.studiodontoiatricodominici.com\/it\/ortodonzia-mobile\/","title":{"rendered":"Ortodonzia Mobile"},"content":{"rendered":"<div id=\"pl-869\"  class=\"panel-layout\" ><div id=\"pg-869-0\"  class=\"panel-grid panel-has-style\" ><div class=\"divider-no-animation panel-row-style panel-row-style-for-869-0\" ><div id=\"pgc-869-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-869-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-0-0-0\" ><div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2>Gli apparecchi mobili in ortodonzia<\/h2>\n<p style=\"text-align: justify;\">Gli apparecchi mobili in ortodonzia sono utilizzati in genere per intervenire su situazioni come disallineamenti dentali o malocclusioni in fase di sviluppo, sono quindi rivolte per lo pi\u00f9 a paziente in et\u00e0 adolescenziale e pre-adolescenziale.<\/p>\n<p style=\"text-align: justify;\">Sono cos\u00ec chiamati perch\u00e9 possono essere inseriti e tolti in autonomia dai pazienti ed inoltre, sono personalizzati perch\u00e9 creati sulla base di un calco delle arcate dentarie e del palato del paziente.<\/p>\n<p style=\"text-align: justify;\">Gli apparecchi mobili sono molto utili per trattare alcuni problemi ortodontici, specie se trattati in et\u00e0 precoce. L\u2019apparecchio mobile, infatti,\u00a0 \u00e8 spesso previsto come fase iniziale di un trattamento di ortodonzia, mentre nella fase finale detta finishing pu\u00f2 essere applicato quello fisso.<\/p>\n<p style=\"text-align: justify;\">Proprio perch\u00e9 mobili, questi apparecchi ortodontici non incidono particolarmente sull\u2019igiene orale, quindi <strong><span style=\"text-decoration: underline;\"><a title=\"Strumenti igiene orale\" href=\"https:\/\/www.studiodontoiatricodominici.com\/it\/igiene-dentale\/igiene-dentale-strumenti\/\">spazzolino e filo interdentale<\/a><\/span><\/strong> possono essere utilizzati tranquillamente.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-869-1\"  class=\"panel-grid panel-has-style\" ><div class=\"divider-no-animation tablet-default mobile-1-in-row panel-row-style panel-row-style-for-869-1\" ><div id=\"pgc-869-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-869-1-0-0\" class=\"so-panel widget widget_orion_heading_w panel-first-child\" data-index=\"1\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-1-0-0\" ><div class=\"so-widget-orion_heading_w so-widget-orion_heading_w-base\"> \r\n\t\t\t<div class=\"row orion-heading\" style=\"margin-bottom:0px;\">\r\n\t\t<div class=\"col-md-12   text-center style-h2 style-text-dark\">\r\n\t\t\t<h2 class=\"text-dark\">\r\n\t\t\t\tOrtodonzia Mobile, come l'apparecchio mobile cambia i denti\t\t\t<\/h2>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<\/div><\/div><\/div><div id=\"panel-869-1-0-1\" class=\"so-panel widget widget_orion_dividers_w panel-last-child\" data-index=\"2\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-1-0-1\" ><div class=\"so-widget-orion_dividers_w so-widget-orion_dividers_w-base\">\t<hr style=\"border-top-width:2px; border-top-color:rgba(242,242,242,1); border-style: solid; width: 100%;  margin-top: 0;\"><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-869-2\"  class=\"panel-grid panel-has-style\" ><div class=\"divider-no-animation tablet-default mobile-1-in-row panel-row-style panel-row-style-for-869-2\" ><div id=\"pgc-869-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-869-2-0-0\" class=\"so-panel widget widget_orion_heading_w panel-first-child\" data-index=\"3\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-2-0-0\" ><div class=\"so-widget-orion_heading_w so-widget-orion_heading_w-base\"> \r\n\t\t\t<div class=\"row orion-heading\" style=\"margin-bottom:0px;\">\r\n\t\t<div class=\"col-md-12   text-center style-h4 style-text-dark\">\r\n\t\t\t<h4 class=\"text-dark\">\r\n\t\t\t\tOrtodonzia Mobile, prima\t\t\t<\/h4>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<\/div><\/div><\/div><div id=\"panel-869-2-0-1\" class=\"so-panel widget widget_orion_image_w panel-last-child\" data-index=\"4\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-2-0-1\" ><div class=\"so-widget-orion_image_w so-widget-orion_image_w-base\">\r\n<div class=\"image-w relative\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"orion_carousel overlay-none overlay-hover-none\">\r\n\t\t\r\n\t\t\t\t\t<img width=\"640\" height=\"480\" src=\"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-content\/uploads\/2018\/02\/apparecchio-denti-mobile-ortodonzia-mobile-prima.jpg\" class=\"attachment-orion_carousel size-orion_carousel\" alt=\"apparecchio denti mobile\" loading=\"lazy\" \/>\t\t\t<div class=\"overlay\"><\/div>\r\n\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\r\n\t<div class=\"absolute\">\r\n\t\t<div class=\"hover-desc table-wrap\">\r\n\t\t\t<div class=\"cell-wrap\">\r\n\t\t\t\t<h4 class=\"primary-color\">ortodonzia mobile prima<\/h4>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t\t\t\t\r\n<\/div>\r\n\r\n<\/div><\/div><\/div><\/div><div id=\"pgc-869-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-869-2-1-0\" class=\"so-panel widget widget_orion_heading_w panel-first-child\" data-index=\"5\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-2-1-0\" ><div class=\"so-widget-orion_heading_w so-widget-orion_heading_w-base\"> \r\n\t\t\t<div class=\"row orion-heading\" style=\"margin-bottom:0px;\">\r\n\t\t<div class=\"col-md-12   text-center style-h4 style-text-dark\">\r\n\t\t\t<h4 class=\"text-dark\">\r\n\t\t\t\tOrtodonzia Mobile dopo\t\t\t<\/h4>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<\/div><\/div><\/div><div id=\"panel-869-2-1-1\" class=\"so-panel widget widget_orion_image_w panel-last-child\" data-index=\"6\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-2-1-1\" ><div class=\"so-widget-orion_image_w so-widget-orion_image_w-base\">\r\n<div class=\"image-w relative\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"orion_carousel overlay-none overlay-hover-none\">\r\n\t\t\r\n\t\t\t\t\t<img width=\"640\" height=\"480\" src=\"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-content\/uploads\/2018\/02\/apparecchio-denti-mobile-ortodonzia-mobile-dopo.jpg\" class=\"attachment-orion_carousel size-orion_carousel\" alt=\"apparecchio denti mobile\" loading=\"lazy\" \/>\t\t\t<div class=\"overlay\"><\/div>\r\n\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\r\n\t<div class=\"absolute\">\r\n\t\t<div class=\"hover-desc table-wrap\">\r\n\t\t\t<div class=\"cell-wrap\">\r\n\t\t\t\t<h4 class=\"primary-color\">ortodonzia mobile dopo<\/h4>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t\t\t\t\r\n<\/div>\r\n\r\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-869-3\"  class=\"panel-grid panel-has-style\" ><div class=\"divider-no-animation tablet-default mobile-1-in-row panel-row-style panel-row-style-for-869-3\" ><div id=\"pgc-869-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-869-3-0-0\" class=\"so-panel widget widget_orion_dividers_w panel-first-child\" data-index=\"7\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-0-0\" ><div class=\"so-widget-orion_dividers_w so-widget-orion_dividers_w-base\">\t<hr style=\"border-top-width:2px; border-top-color:rgba(242,242,242,1); border-style: solid; width: 100%;  margin-top: 0;\"><\/div><\/div><\/div><div id=\"panel-869-3-0-1\" class=\"so-panel widget widget_orion_heading_w\" data-index=\"8\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-0-1\" ><div class=\"so-widget-orion_heading_w so-widget-orion_heading_w-base\"> \r\n\t\t\t<div class=\"row orion-heading\" style=\"margin-bottom:0px;\">\r\n\t\t<div class=\"col-md-12   text-center style-h4 style-text-dark\">\r\n\t\t\t<h4 class=\"text-dark\">\r\n\t\t\t\tOrtodonzia Mobile, prima\t\t\t<\/h4>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<\/div><\/div><\/div><div id=\"panel-869-3-0-2\" class=\"so-panel widget widget_orion_image_w panel-last-child\" data-index=\"9\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-0-2\" ><div class=\"so-widget-orion_image_w so-widget-orion_image_w-base\">\r\n<div class=\"image-w relative\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"orion_carousel overlay-none overlay-hover-none\">\r\n\t\t\r\n\t\t\t\t\t<img width=\"640\" height=\"480\" src=\"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-content\/uploads\/2018\/02\/apparecchio-denti-mobile-ortodonzia-mobile-2-prima.jpg\" class=\"attachment-orion_carousel size-orion_carousel\" alt=\"apparecchio denti mobile\" loading=\"lazy\" \/>\t\t\t<div class=\"overlay\"><\/div>\r\n\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\r\n\t<div class=\"absolute\">\r\n\t\t<div class=\"hover-desc table-wrap\">\r\n\t\t\t<div class=\"cell-wrap\">\r\n\t\t\t\t<h4 class=\"primary-color\">ortodonzia mobile prima<\/h4>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t\t\t\t\r\n<\/div>\r\n\r\n<\/div><\/div><\/div><\/div><div id=\"pgc-869-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-869-3-1-0\" class=\"so-panel widget widget_orion_dividers_w panel-first-child\" data-index=\"10\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-1-0\" ><div class=\"so-widget-orion_dividers_w so-widget-orion_dividers_w-base\">\t<hr style=\"border-top-width:2px; border-top-color:rgba(242,242,242,1); border-style: solid; width: 100%;  margin-top: 0;\"><\/div><\/div><\/div><div id=\"panel-869-3-1-1\" class=\"so-panel widget widget_orion_heading_w\" data-index=\"11\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-1-1\" ><div class=\"so-widget-orion_heading_w so-widget-orion_heading_w-base\"> \r\n\t\t\t<div class=\"row orion-heading\" style=\"margin-bottom:0px;\">\r\n\t\t<div class=\"col-md-12   text-center style-h4 style-text-dark\">\r\n\t\t\t<h4 class=\"text-dark\">\r\n\t\t\t\tOrtodonzia Mobile dopo\t\t\t<\/h4>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\r\n\t<\/div><\/div><\/div><div id=\"panel-869-3-1-2\" class=\"so-panel widget widget_orion_image_w panel-last-child\" data-index=\"12\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-3-1-2\" ><div class=\"so-widget-orion_image_w so-widget-orion_image_w-base\">\r\n<div class=\"image-w relative\">\r\n\r\n\t\t\t\t\t\t\t<div class=\"orion_carousel overlay-none overlay-hover-none\">\r\n\t\t\r\n\t\t\t\t\t<img width=\"640\" height=\"480\" src=\"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-content\/uploads\/2018\/02\/apparecchio-denti-mobile-ortodonzia-mobile-2-dopo.jpg\" class=\"attachment-orion_carousel size-orion_carousel\" alt=\"apparecchio denti mobile\" loading=\"lazy\" \/>\t\t\t<div class=\"overlay\"><\/div>\r\n\t\t\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\r\n\t\r\n\t<div class=\"absolute\">\r\n\t\t<div class=\"hover-desc table-wrap\">\r\n\t\t\t<div class=\"cell-wrap\">\r\n\t\t\t\t<h4 class=\"primary-color\">ortodonzia mobile dopo<\/h4>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t<\/div>\t\t\t\t\t\r\n<\/div>\r\n\r\n<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-869-4\"  class=\"panel-grid panel-has-style\" ><div class=\"divider-no-animation tablet-default mobile-1-in-row panel-row-style panel-row-style-for-869-4\" ><div id=\"pgc-869-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-869-4-0-0\" class=\"so-panel widget widget_orion_dividers_w panel-first-child\" data-index=\"13\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-4-0-0\" ><div class=\"so-widget-orion_dividers_w so-widget-orion_dividers_w-base\">\t<hr style=\"border-top-width:2px; border-top-color:rgba(242,242,242,1); border-style: solid; width: 100%;  margin-top: 0;\"><\/div><\/div><\/div><div id=\"panel-869-4-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"14\" ><div class=\"orion default panel-widget-style panel-widget-style-for-869-4-0-1\" ><div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: justify;\">\u00a0<\/p>\n<h3><strong>Tipologie di apparecchi mobili<\/strong><\/h3>\n<p style=\"text-align: justify;\">Ci sono tre tipi di apparecchi mobili:<\/p>\n<ul>\n<li style=\"text-align: justify;\"><b>Apparecchio mobile meccanico: <\/b>la forza attiva \u00e8 attivata dalle viti, dalle molle e dagli archi che compongono l\u2019apparecchio.<\/li>\n<li style=\"text-align: justify;\"><b>Apparecchio mobile funzionale: <\/b>agisce grazie alla forza delle labbra, della lingua e dei muscoli della masticazione.Con questo apparecchio si ottiene sia lo spostamento dei denti che una vera e propria azione ortopedica, in grado di indirizzare una corretta posizione della zona ossea mandibolare e mascellare, oltre che correggere malocclusioni.<\/li>\n<li style=\"text-align: justify;\"><b>Apparecchio mobile di mantenimento: <\/b>si utilizza alla fine del trattamento per mantenere il risultato che si \u00e8 raggiunto. Normalmente questo tipo apparecchio mobile, si porta durante la notte, ma questo va poi definito con il professionista di fiducia in quanto varia da caso a caso.<\/li>\n<\/ul>\n<h3><strong>Per saperne di pi\u00f9,<span style=\"text-decoration: underline;\"><a title=\"Contatti\" href=\"https:\/\/www.studiodontoiatricodominici.com\/it\/contatti-studio-dentistico-roma-eur\/\">prenota una visita con il nostro ortodontista!<\/a><\/span><\/strong><\/h3>\n<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f1529-o1\" lang=\"it-IT\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/869#wpcf7-f1529-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"1529\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1529-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"cf7-form row\">\n<div class=\"col-md-6 name\"><span class=\"wpcf7-form-control-wrap text-name\"><input type=\"text\" name=\"text-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" \/><\/span><\/div>\n<div class=\"col-md-6 name\"><span class=\"wpcf7-form-control-wrap text-last-name\"><input type=\"text\" name=\"text-last-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cognome\" \/><\/span><\/div>\n<div class=\"col-md-6 phone\"><span class=\"wpcf7-form-control-wrap text-phone\"><input type=\"text\" name=\"text-phone\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Numero di Telefono\" \/><\/span><\/div>\n<div class=\"col-md-6 email\"><span class=\"wpcf7-form-control-wrap email-777\"><input type=\"email\" name=\"email-777\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" \/><\/span><\/div>\n<div class=\"col-md-12 select\"><span class=\"wpcf7-form-control-wrap menu-reason\"><select name=\"menu-reason\" class=\"wpcf7-form-control wpcf7-select form-control\" aria-invalid=\"false\"><option value=\"Prima Visita\">Prima Visita<\/option><option value=\"Pulizia\">Pulizia<\/option><option value=\"Consulto\">Consulto<\/option><option value=\"Trattamento\">Trattamento<\/option><option value=\"Visita Urgente\">Visita Urgente<\/option><option value=\"Altro\">Altro<\/option><\/select><\/span><\/div>\n<div class=\"col-md-12\"><span class=\"wpcf7-form-control-wrap textarea-notes\"><textarea name=\"textarea-notes\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Info sul problema ed il giorno pi\u00f9 utile per l&#039;appuntamento\"><\/textarea><\/span><\/div>\n<div class=\"col-md-12 text-left\"><input type=\"submit\" value=\"Richiedi Appuntamento\" class=\"wpcf7-form-control has-spinner wpcf7-submit btn btn-c1 btn-lg\" \/><\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Gli apparecchi mobili in ortodonzia Gli apparecchi mobili in ortodonzia sono utilizzati in genere per intervenire su situazioni come disallineamenti dentali o malocclusioni in fase di sviluppo, sono quindi rivolte per lo pi\u00f9 a paziente in et\u00e0 adolescenziale e pre-adolescenziale. Sono cos\u00ec chiamati perch\u00e9 possono essere inseriti e tolti in autonomia dai pazienti ed inoltre,<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/pages\/869"}],"collection":[{"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":29,"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/pages\/869\/revisions"}],"predecessor-version":[{"id":2941,"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/pages\/869\/revisions\/2941"}],"wp:attachment":[{"href":"https:\/\/www.studiodontoiatricodominici.com\/it\/wp-json\/wp\/v2\/media?parent=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}